{"id":390,"count":10,"description":"A","link":"https:\/\/saxcompany.nl\/en\/product-category\/all-accessories\/caps\/alto-caps\/","name":"Alto","slug":"alto-caps","taxonomy":"product_cat","parent":389,"meta":[],"menu_order":6,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alto Archives - SaxCompany.nl<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/saxcompany.nl\/en\/product-category\/all-accessories\/caps\/alto-caps\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alto Archives - SaxCompany.nl\" \/>\n<meta property=\"og:description\" content=\"A\" \/>\n<meta property=\"og:url\" content=\"https:\/\/saxcompany.nl\/en\/product-category\/all-accessories\/caps\/alto-caps\/\" \/>\n<meta property=\"og:site_name\" content=\"SaxCompany.nl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/saxcompany.nl\\\/en\\\/product-category\\\/all-accessories\\\/caps\\\/alto-caps\\\/\",\"url\":\"https:\\\/\\\/saxcompany.nl\\\/en\\\/product-category\\\/all-accessories\\\/caps\\\/alto-caps\\\/\",\"name\":\"Alto Archives - SaxCompany.nl\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/saxcompany.nl\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/saxcompany.nl\\\/en\\\/product-category\\\/all-accessories\\\/caps\\\/alto-caps\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/saxcompany.nl\\\/en\\\/product-category\\\/all-accessories\\\/caps\\\/alto-caps\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/saxcompany.nl\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"All accessories\",\"item\":\"https:\\\/\\\/saxcompany.nl\\\/en\\\/product-category\\\/all-accessories\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Caps\",\"item\":\"https:\\\/\\\/saxcompany.nl\\\/en\\\/product-category\\\/all-accessories\\\/caps\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Alto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/saxcompany.nl\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/saxcompany.nl\\\/en\\\/\",\"name\":\"SaxCompany.nl\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/saxcompany.nl\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/saxcompany.nl\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/saxcompany.nl\\\/en\\\/#organization\",\"name\":\"Saxcompany.nl\",\"url\":\"https:\\\/\\\/saxcompany.nl\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/saxcompany.nl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/saxcompany.nl\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-nl.png\",\"contentUrl\":\"https:\\\/\\\/saxcompany.nl\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-nl.png\",\"width\":269,\"height\":71,\"caption\":\"Saxcompany.nl\"},\"image\":{\"@id\":\"https:\\\/\\\/saxcompany.nl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alto Archives - SaxCompany.nl","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/saxcompany.nl\/en\/product-category\/all-accessories\/caps\/alto-caps\/","og_locale":"en_US","og_type":"article","og_title":"Alto Archives - SaxCompany.nl","og_description":"A","og_url":"https:\/\/saxcompany.nl\/en\/product-category\/all-accessories\/caps\/alto-caps\/","og_site_name":"SaxCompany.nl","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/saxcompany.nl\/en\/product-category\/all-accessories\/caps\/alto-caps\/","url":"https:\/\/saxcompany.nl\/en\/product-category\/all-accessories\/caps\/alto-caps\/","name":"Alto Archives - SaxCompany.nl","isPartOf":{"@id":"https:\/\/saxcompany.nl\/en\/#website"},"breadcrumb":{"@id":"https:\/\/saxcompany.nl\/en\/product-category\/all-accessories\/caps\/alto-caps\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/saxcompany.nl\/en\/product-category\/all-accessories\/caps\/alto-caps\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/saxcompany.nl\/en\/"},{"@type":"ListItem","position":2,"name":"All accessories","item":"https:\/\/saxcompany.nl\/en\/product-category\/all-accessories\/"},{"@type":"ListItem","position":3,"name":"Caps","item":"https:\/\/saxcompany.nl\/en\/product-category\/all-accessories\/caps\/"},{"@type":"ListItem","position":4,"name":"Alto"}]},{"@type":"WebSite","@id":"https:\/\/saxcompany.nl\/en\/#website","url":"https:\/\/saxcompany.nl\/en\/","name":"SaxCompany.nl","description":"","publisher":{"@id":"https:\/\/saxcompany.nl\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/saxcompany.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/saxcompany.nl\/en\/#organization","name":"Saxcompany.nl","url":"https:\/\/saxcompany.nl\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/saxcompany.nl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/saxcompany.nl\/wp-content\/uploads\/2024\/03\/logo-nl.png","contentUrl":"https:\/\/saxcompany.nl\/wp-content\/uploads\/2024\/03\/logo-nl.png","width":269,"height":71,"caption":"Saxcompany.nl"},"image":{"@id":"https:\/\/saxcompany.nl\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/saxcompany.nl\/en\/wp-json\/wp\/v2\/product_cat\/390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saxcompany.nl\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/saxcompany.nl\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/saxcompany.nl\/en\/wp-json\/wp\/v2\/product_cat\/389"}],"wp:post_type":[{"href":"https:\/\/saxcompany.nl\/en\/wp-json\/wp\/v2\/product?product_cat=390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}